{"id":1828,"date":"2020-02-27T13:31:16","date_gmt":"2020-02-27T13:31:16","guid":{"rendered":"https:\/\/carflow.pro\/?p=1828"},"modified":"2020-05-26T10:05:33","modified_gmt":"2020-05-26T10:05:33","slug":"google-analytics","status":"publish","type":"post","link":"https:\/\/carflow.pro\/fr\/marketing-en-ligne\/google-analytics\/","title":{"rendered":"Que devez-vous savoir sur Google Analytics en tant que concessionnaire automobile ?"},"content":{"rendered":"\n<p>Vous obtenez des visiteurs sur votre site Web, mais savez-vous qui ils sont ou d&#8217;o\u00f9 ils viennent&nbsp;? Il existe une multitude de donn\u00e9es disponibles sur ces visiteurs. Vous pouvez acc\u00e9der \u00e0 ces donn\u00e9es de mani\u00e8re simple en utilisant Google Analytics. Ces informations sont importantes pour tous les secteurs et donc indispensables pour le secteur automobile. Google Analytics fournit entre autres des informations sur l&#8217;origine des visiteurs de votre showroom virtuelle. Cela s&#8217;applique \u00e9galement au comportement des visiteurs. En outre, il s&#8217;agit d&#8217;un excellent outil pour d\u00e9terminer les canaux de commercialisation que les visiteurs peuvent ou non convertir. Nous \u00e9num\u00e9rons ci-dessous les param\u00e8tres les plus importants.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"488\" src=\"https:\/\/carflow.pro\/wp-content\/uploads\/2020\/02\/fullsizeoutput_1c6-1024x488.jpeg\" alt=\"\" class=\"wp-image-1801\" srcset=\"https:\/\/carflow.pro\/wp-content\/uploads\/2020\/02\/fullsizeoutput_1c6-1024x488.jpeg 1024w, https:\/\/carflow.pro\/wp-content\/uploads\/2020\/02\/fullsizeoutput_1c6-300x143.jpeg 300w, https:\/\/carflow.pro\/wp-content\/uploads\/2020\/02\/fullsizeoutput_1c6-768x366.jpeg 768w, https:\/\/carflow.pro\/wp-content\/uploads\/2020\/02\/fullsizeoutput_1c6-1536x732.jpeg 1536w, https:\/\/carflow.pro\/wp-content\/uploads\/2020\/02\/fullsizeoutput_1c6.jpeg 1747w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>L&#8217;importance d&#8217;objectifs pr\u00e9d\u00e9termin\u00e9s<\/strong><\/h2>\n\n\n\n<p>D\u00e9terminez les\nobjectifs que vous souhaitez mesurer et d\u00e9finissez-les en tant que conversion.\nDe cette fa\u00e7on, vous pourrez facilement mesurer les performances d&#8217;\u00e9l\u00e9ments\nsp\u00e9cifiques de votre site Web. Par exemple, vous mesurez combien de personnes\ndemandent un essai routier ou remplissent le formulaire de contact.<\/p>\n\n\n\n<p>Bien s\u00fbr, toutes les conversions n&#8217;ont pas la m\u00eame valeur pour votre entreprise. Une demande d&#8217;essai routier peut \u00eatre plus utile qu&#8217;un rendez-vous technique. Attribuez des valeurs \u00e0 vos conversions afin d&#8217;optimiser la valeur au lieu du nombre de conversions. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Nombre mensuel de visiteurs et caract\u00e9ristiques des visiteurs<\/strong><\/h2>\n\n\n\n<p>Google Analytics\ndonne un aper\u00e7u du nombre de visiteurs et vous permet d&#8217;en analyser les\ncaract\u00e9ristiques Entre autres, il est possible de suivre l&#8217;\u00e9volution du nombre\nde visiteurs sur votre site. Y a-t-il une croissance notable ou cela varie-t-il\nd\u2019un mois \u00e0 l\u2019autre&nbsp;? Dans le secteur automobile, il y a des p\u00e9riodes o\u00f9\nles ventes augmentent et d\u2019autres, o\u00f9 elles diminuent. \u00c0 cet \u00e9gard, la saison\ninflue fortement sur les ventes de voiture. Vous d\u00e9couvrirez \u00e9galement quelles\np\u00e9riodes sont importantes pour vous en tant que concessionnaire automobile.\nPensez par exemple au salon de l&#8217;automobile. Avec ces donn\u00e9es \u00e0 l&#8217;esprit, vous\npouvez r\u00e9pondre de mani\u00e8re optimale aux mois calmes et intenses. <\/p>\n\n\n\n<p>Google Analytics\noffre un aper\u00e7u num\u00e9rique de ce qui se passe dans votre showroom virtuel. Cela\npeut \u00eatre compar\u00e9 aux visites physiques dans votre showroom et aux ventes de\nvoitures associ\u00e9es.<\/p>\n\n\n\n<p>Non seulement le\nnombre de visiteurs mais aussi leurs caract\u00e9ristiques sont une mesure\nimportante. Vous pouvez les d\u00e9duire en interpr\u00e9tant les donn\u00e9es dans Google Analytics.\nLe temps qu&#8217;un utilisateur passe sur votre site Web fournit une indication\nimportante. <\/p>\n\n\n\n<p>Par exemple, il est\nint\u00e9ressant de d\u00e9couvrir le canal \u00e0 travers lequel les visiteurs sont pr\u00e9sents\nle plus longtemps. Ou de voir quel canal offre un taux de rebond \u00e9lev\u00e9. Le taux\nde rebond repr\u00e9sente un pourcentage de visiteurs qui visitent une page et\npartent sans autre action. Dans ce cas, la dur\u00e9e de la visite compte pour z\u00e9ro\nseconde.<\/p>\n\n\n\n<p>Les visiteurs qui reviennent sont aussi importants car ce sont des clients potentiels avec de fortes probabilit\u00e9s de conversion. Il arrive souvent que les visiteurs int\u00e9ress\u00e9s reviennent plus souvent parce qu&#8217;ils veulent \u00eatre correctement inform\u00e9s. Ensuite, les probabilit\u00e9s d&#8217;achat sont plus grandes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Trafic organique<\/strong><\/h2>\n\n\n\n<p>Google Analytics\nvous montre \u00e9galement quels visiteurs ont visit\u00e9 votre site Web via le trafic\norganique. Le trafic organique signifie le trafic avec, par exemple, le moteur\nde recherche Google. Donc, les utilisateurs de votre site Web qui ont saisi une\nrequ\u00eate de recherche, a inclus votre site Web dans les r\u00e9sultats. Le\nr\u00e9f\u00e9rencement est gratuit et ne doit pas \u00eatre confondu avec le SEA, pour lequel\nvous devez payer. Si votre site Web augmente dans le classement des r\u00e9sultats\nde recherche, vous remarquerez une augmentation organique du nombre de\nvisiteurs du site. <\/p>\n\n\n\n<p><strong>Conseil<\/strong>&nbsp;: configurez la Console Google Search \u00e0 des fins de r\u00e9f\u00e9rencement et cr\u00e9ez un lien avec Google Analytics pour obtenir des informations suppl\u00e9mentaires.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Trafic payant<\/strong><\/h2>\n\n\n\n<p>Lorsque vous\nd\u00e9marrez une campagne publicitaire payante, vous voulez naturellement savoir\nquels en sont les r\u00e9sultats. Dans Google Analytics, vous pouvez d\u00e9couvrir\nquelle campagne a g\u00e9n\u00e9r\u00e9 le plus de conversions. Il est aussi int\u00e9ressant de\nvoir quels mots cl\u00e9s g\u00e9n\u00e8rent le plus de trafic et g\u00e9n\u00e8re le meilleur taux de\nconversion. Sur la base de ces informations, vous pouvez apporter des\nmodifications budg\u00e9taires r\u00e9fl\u00e9chies ou ajuster d&#8217;autres aspects structurels. <\/p>\n\n\n\n<p>Google Analytics\nest un outil indispensable pour obtenir un aper\u00e7u des donn\u00e9es importantes. En\noutre, c&#8217;est un excellent moyen de mieux comprendre vos efforts de marketing,\nidentifier les canaux que vous devez optimiser davantage et o\u00f9 le chiffre\nd\u2019affaires est le plus \u00e9lev\u00e9. Gr\u00e2ce \u00e0 Google Analytics, vous pouvez voir combien\nde personnes ont visit\u00e9 votre showroom virtuel. Ces donn\u00e9es de base sont tr\u00e8s\nfaciles \u00e0 collecter. Vous n&#8217;avez besoin que d&#8217;un compte pour commencer et\ninstaller un code de suivi sur votre site Web.<\/p>\n\n\n\n<p><em>Carflow\naide votre entreprise automobile par des solutions num\u00e9riques avant-gardistes\ndans les ventes, le marketing, la gestion des stocks, les publications, les\ninformations, l\u2019\u00e9tablissement de rapports et bien plus encore. N&#8217;h\u00e9sitez pas \u00e0<\/em> <em>nous<\/em> <a href=\"https:\/\/carflow.pro\/contact\/\"><em>contacter<\/em><\/a> <em>pour d\u00e9couvrir ce que nous pouvons\nfaire pour vous&nbsp;!<\/em><em><\/em><\/p>\n\n\n\n<p>Vous souhaitez en savoir plus sur la mani\u00e8re dont les\nconcessions num\u00e9riques surmontent la concurrence&nbsp;? Inscrivez-vous et\nrecevez notre livre blanc sur la concession du futur.<\/p>\n\n\n\n<div class=\"wp-block-button button button--primary is-style-squared\"><a class=\"wp-block-button__link\" href=\"https:\/\/carflow.pro\/fr\/le-concessionaire-du-futur\/\">T\u00e9l\u00e9chargez notre livre blanc<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vous obtenez des visiteurs sur votre site Web, mais savez-vous qui ils sont ou d&#8217;o\u00f9 ils viennent&nbsp;? Il existe une multitude de donn\u00e9es disponibles sur ces visiteurs. Vous pouvez acc\u00e9der \u00e0 ces donn\u00e9es de mani\u00e8re simple en utilisant Google Analytics. Ces informations sont importantes pour tous les secteurs et donc indispensables pour le secteur automobile. [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/carflow.pro\/fr\/marketing-en-ligne\/google-analytics\/\">Lire la suite&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Que devez-vous savoir sur Google Analytics en tant que concessionnaire automobile ? - Carflow<\/title>\n<meta name=\"description\" content=\"Vous obtenez des visiteurs sur votre site Web, mais savez-vous qui ils sont ou d&#039;o\u00f9 ils viennent ? Vous pouvez acc\u00e9der \u00e0 ces donn\u00e9es en utilisant Google Analytics.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/carflow.pro\/fr\/marketing-en-ligne\/google-analytics\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Que devez-vous savoir sur Google Analytics en tant que concessionnaire automobile ? - Carflow\" \/>\n<meta property=\"og:description\" content=\"Vous obtenez des visiteurs sur votre site Web, mais savez-vous qui ils sont ou d&#039;o\u00f9 ils viennent ? Vous pouvez acc\u00e9der \u00e0 ces donn\u00e9es en utilisant Google Analytics.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/carflow.pro\/fr\/marketing-en-ligne\/google-analytics\/\" \/>\n<meta property=\"og:site_name\" content=\"Carflow\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-27T13:31:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-26T10:05:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/carflow.pro\/wp-content\/uploads\/2020\/02\/fullsizeoutput_1c6-1024x488.jpeg\" \/>\n<meta name=\"author\" content=\"IT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"IT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Que devez-vous savoir sur Google Analytics en tant que concessionnaire automobile ? - Carflow","description":"Vous obtenez des visiteurs sur votre site Web, mais savez-vous qui ils sont ou d'o\u00f9 ils viennent ? Vous pouvez acc\u00e9der \u00e0 ces donn\u00e9es en utilisant Google Analytics.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/carflow.pro\/fr\/marketing-en-ligne\/google-analytics\/","og_locale":"fr_FR","og_type":"article","og_title":"Que devez-vous savoir sur Google Analytics en tant que concessionnaire automobile ? - Carflow","og_description":"Vous obtenez des visiteurs sur votre site Web, mais savez-vous qui ils sont ou d'o\u00f9 ils viennent ? Vous pouvez acc\u00e9der \u00e0 ces donn\u00e9es en utilisant Google Analytics.","og_url":"https:\/\/carflow.pro\/fr\/marketing-en-ligne\/google-analytics\/","og_site_name":"Carflow","article_published_time":"2020-02-27T13:31:16+00:00","article_modified_time":"2020-05-26T10:05:33+00:00","og_image":[{"url":"https:\/\/carflow.pro\/wp-content\/uploads\/2020\/02\/fullsizeoutput_1c6-1024x488.jpeg"}],"author":"IT","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"IT","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/carflow.pro\/fr\/marketing-en-ligne\/google-analytics\/#article","isPartOf":{"@id":"https:\/\/carflow.pro\/fr\/marketing-en-ligne\/google-analytics\/"},"author":{"name":"IT","@id":"https:\/\/carflow.pro\/fr\/#\/schema\/person\/800c3660a9e60c237d0a1044703ccb2d"},"headline":"Que devez-vous savoir sur Google Analytics en tant que concessionnaire automobile ?","datePublished":"2020-02-27T13:31:16+00:00","dateModified":"2020-05-26T10:05:33+00:00","mainEntityOfPage":{"@id":"https:\/\/carflow.pro\/fr\/marketing-en-ligne\/google-analytics\/"},"wordCount":944,"commentCount":0,"publisher":{"@id":"https:\/\/carflow.pro\/fr\/#organization"},"articleSection":["Marketing en ligne"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/carflow.pro\/fr\/marketing-en-ligne\/google-analytics\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/carflow.pro\/fr\/marketing-en-ligne\/google-analytics\/","url":"https:\/\/carflow.pro\/fr\/marketing-en-ligne\/google-analytics\/","name":"Que devez-vous savoir sur Google Analytics en tant que concessionnaire automobile ? - Carflow","isPartOf":{"@id":"https:\/\/carflow.pro\/fr\/#website"},"datePublished":"2020-02-27T13:31:16+00:00","dateModified":"2020-05-26T10:05:33+00:00","description":"Vous obtenez des visiteurs sur votre site Web, mais savez-vous qui ils sont ou d'o\u00f9 ils viennent ? Vous pouvez acc\u00e9der \u00e0 ces donn\u00e9es en utilisant Google Analytics.","breadcrumb":{"@id":"https:\/\/carflow.pro\/fr\/marketing-en-ligne\/google-analytics\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/carflow.pro\/fr\/marketing-en-ligne\/google-analytics\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/carflow.pro\/fr\/marketing-en-ligne\/google-analytics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/carflow.pro\/fr\/"},{"@type":"ListItem","position":2,"name":"Que devez-vous savoir sur Google Analytics en tant que concessionnaire automobile ?"}]},{"@type":"WebSite","@id":"https:\/\/carflow.pro\/fr\/#website","url":"https:\/\/carflow.pro\/fr\/","name":"Carflow","description":"En nog een WordPress website","publisher":{"@id":"https:\/\/carflow.pro\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/carflow.pro\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/carflow.pro\/fr\/#organization","name":"Carflow","url":"https:\/\/carflow.pro\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/carflow.pro\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/carflow.pro\/wp-content\/uploads\/2019\/01\/cf-logo.png","contentUrl":"https:\/\/carflow.pro\/wp-content\/uploads\/2019\/01\/cf-logo.png","width":300,"height":61,"caption":"Carflow"},"image":{"@id":"https:\/\/carflow.pro\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/carflow.pro\/fr\/#\/schema\/person\/800c3660a9e60c237d0a1044703ccb2d","name":"IT","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/carflow.pro\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/daaf13cf5d32acc87207204ed6afe351?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/daaf13cf5d32acc87207204ed6afe351?s=96&d=mm&r=g","caption":"IT"}}]}},"_links":{"self":[{"href":"https:\/\/carflow.pro\/fr\/wp-json\/wp\/v2\/posts\/1828"}],"collection":[{"href":"https:\/\/carflow.pro\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carflow.pro\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carflow.pro\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/carflow.pro\/fr\/wp-json\/wp\/v2\/comments?post=1828"}],"version-history":[{"count":4,"href":"https:\/\/carflow.pro\/fr\/wp-json\/wp\/v2\/posts\/1828\/revisions"}],"predecessor-version":[{"id":2219,"href":"https:\/\/carflow.pro\/fr\/wp-json\/wp\/v2\/posts\/1828\/revisions\/2219"}],"wp:attachment":[{"href":"https:\/\/carflow.pro\/fr\/wp-json\/wp\/v2\/media?parent=1828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carflow.pro\/fr\/wp-json\/wp\/v2\/categories?post=1828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carflow.pro\/fr\/wp-json\/wp\/v2\/tags?post=1828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}